{"id":6791,"date":"2022-02-25T14:54:40","date_gmt":"2022-02-25T12:54:40","guid":{"rendered":"https:\/\/www.asterix-friends.com\/?p=6791"},"modified":"2022-02-25T17:53:52","modified_gmt":"2022-02-25T15:53:52","slug":"asterix-ses-amis-remasterise-la-nouvelle-villageoise-taillefine","status":"publish","type":"post","link":"https:\/\/www.asterix-friends.com\/fr\/asterix-ses-amis-remasterise-la-nouvelle-villageoise-taillefine\/","title":{"rendered":"Ast\u00e9rix &#038; ses Amis remasteris\u00e9 &#8211; La nouvelle villageoise Taillefine"},"content":{"rendered":"<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ch\u00e8res Gauloises, chers Gaulois,\\n\\nPour c\u00e9l\u00e9brer la sortie d'Ast\u00e9rix &amp; ses Amis Remasteris\u00e9, nous aimerions vous pr\u00e9senter les nouvelles fonctionnalit\u00e9s dans des articles s\u00e9par\u00e9s !\\nCette fois, nous parlons de Taillefine, la nouvelle villageoise !\\n\\nSon histoire commence par une enqu\u00eate en juin 2020. Pour des raisons \u00e9videntes, l'enqu\u00eate a r\u00e9v\u00e9l\u00e9 un grand int\u00e9r\u00eat pour une villageoise ! Apr\u00e8s un certain temps, nous avons commenc\u00e9 \u00e0 travailler sur le premier concept art et son histoire. Pendant que nos game designers \u00e9crivaient les qu\u00eates et d\u00e9cidaient des r\u00e9compenses, les game artists finalisaient la conception du personnage de Taillefine et cr\u00e9aient son mod\u00e8le en 3D.\\n\\nPour la faire ressortir des autres personnages et du fond d\u2019herbe, nous avons opt\u00e9 pour des cheveux roux et une robe bleue ! En tant qu'\u00e9pouse de Soul\u00e9tropix, Taillefine vit \u00e9galement dans sa maison, nous n'avons donc pr\u00e9vu aucune habitation pour elle. Cependant, nous avons souhait\u00e9 ajouter un nouvel espace et avons d\u00e9cid\u00e9 d'un jardin, parfait pour elle en tant qu\u2019amoureuse de la nature !\\n\\nTaillefine reviendra de Lut\u00e8ce \u00e0 votre village apr\u00e8s que vous ayez construit la maison du forgeron et le jardin de Taillefine, apr\u00e8s avoir atteint le niveau 28 !\\nElle combattra aux c\u00f4t\u00e9s de Joystix et des autres personnages dans les bagarres de village ainsi que contre les Romains, et elle ajoutera \u00e9galement environ 60 missions au jeu !\\nDe nombreuses qu\u00eates uniques sont incluses et apparaissent \u00e0 partir du niveau 28, et 15 missions r\u00e9p\u00e9tables reviennent apr\u00e8s une semaine, ou apr\u00e8s 16, 32 ou 72 heures. Avec Taillefine, des qu\u00eates de niveau 71 \u00e0 80 trouveront \u00e9galement leur place dans le jeu.\\nNous esp\u00e9rons que vou appr\u00e9cierez Taillefine autant que nous !\\n\\nVotre \u00c9quipe Ast\u00e9rix &amp; ses Amis\\n&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:4993,&quot;3&quot;:{&quot;1&quot;:0},&quot;10&quot;:0,&quot;11&quot;:4,&quot;12&quot;:0,&quot;15&quot;:&quot;Arial&quot;}\">Ch\u00e8res Gauloises, chers Gaulois,<\/span><\/p>\n<p>Pour c\u00e9l\u00e9brer la sortie d&rsquo;Ast\u00e9rix &amp; ses Amis Remasteris\u00e9, nous aimerions vous pr\u00e9senter les nouvelles fonctionnalit\u00e9s dans des articles s\u00e9par\u00e9s !<br \/>\nCette fois, nous parlons de Taillefine, la nouvelle villageoise !<\/p>\n<p>Son histoire commence par une enqu\u00eate en juin 2020. Pour des raisons \u00e9videntes, l&rsquo;enqu\u00eate a r\u00e9v\u00e9l\u00e9 un grand int\u00e9r\u00eat pour une villageoise ! Apr\u00e8s un certain temps, nous avons commenc\u00e9 \u00e0 travailler sur le premier concept art et son histoire. Pendant que nos game designers \u00e9crivaient les qu\u00eates et d\u00e9cidaient des r\u00e9compenses, les game artists finalisaient la conception du personnage de Taillefine et cr\u00e9aient son mod\u00e8le en 3D.<\/p>\n<p><a href=\"https:\/\/www.asterix-friends.com\/wp-content\/uploads\/2022\/02\/Gardenia_FR-1.png\" rel=\"shadowbox[sbpost-6791];player=img;\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-6783\" src=\"https:\/\/www.asterix-friends.com\/wp-content\/uploads\/2022\/02\/Gardenia_FR-1.png\" alt=\"\" width=\"700\" height=\"900\" srcset=\"https:\/\/www.asterix-friends.com\/wp-content\/uploads\/2022\/02\/Gardenia_FR-1.png 700w, https:\/\/www.asterix-friends.com\/wp-content\/uploads\/2022\/02\/Gardenia_FR-1-233x300.png 233w, https:\/\/www.asterix-friends.com\/wp-content\/uploads\/2022\/02\/Gardenia_FR-1-624x802.png 624w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>Pour la faire ressortir des autres personnages et du fond d\u2019herbe, nous avons opt\u00e9 pour des cheveux roux et une robe bleue ! En tant qu&rsquo;\u00e9pouse de Soul\u00e9tropix, Taillefine vit \u00e9galement dans sa maison, nous n&rsquo;avons donc pr\u00e9vu aucune habitation pour elle. Cependant, nous avons souhait\u00e9 ajouter un nouvel espace et avons d\u00e9cid\u00e9 d&rsquo;un jardin, parfait pour elle en tant qu\u2019amoureuse de la nature !<\/p>\n<p>Taillefine reviendra de Lut\u00e8ce \u00e0 votre village apr\u00e8s que vous ayez construit la maison du forgeron et le jardin de Taillefine, apr\u00e8s avoir atteint le niveau 28 !<br \/>\nElle combattra aux c\u00f4t\u00e9s de Joystix et des autres personnages dans les bagarres de village ainsi que contre les Romains, et elle ajoutera \u00e9galement environ 60 missions au jeu !<br \/>\nDe nombreuses qu\u00eates uniques sont incluses et apparaissent \u00e0 partir du niveau 28, et 15 missions r\u00e9p\u00e9tables reviennent apr\u00e8s une semaine, ou apr\u00e8s 16, 32 ou 72 heures. Avec Taillefine, des qu\u00eates de niveau 71 \u00e0 80 trouveront \u00e9galement leur place dans le jeu.<br \/>\nNous esp\u00e9rons que vou appr\u00e9cierez Taillefine autant que nous !<\/p>\n<p>Votre \u00c9quipe Ast\u00e9rix &amp; ses Amis<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ch\u00e8res Gauloises, chers Gaulois, Pour c\u00e9l\u00e9brer la sortie d&rsquo;Ast\u00e9rix &amp; ses Amis Remasteris\u00e9, nous aimerions vous pr\u00e9senter les nouvelles fonctionnalit\u00e9s [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[4],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ast\u00e9rix &amp; ses Amis remasteris\u00e9 - La nouvelle villageoise Taillefine - Asterix &amp; Friends - Official Website<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asterix-friends.com\/fr\/asterix-ses-amis-remasterise-la-nouvelle-villageoise-taillefine\/\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asterix-friends.com\/de\/#website\",\"url\":\"https:\/\/www.asterix-friends.com\/de\/\",\"name\":\"Asterix &amp; Friends - Official Website\",\"description\":\"Asterix &amp; Friends - the official Online and Mobile Game\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asterix-friends.com\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.asterix-friends.com\/fr\/asterix-ses-amis-remasterise-la-nouvelle-villageoise-taillefine\/#primaryimage\",\"url\":\"https:\/\/www.asterix-friends.com\/wp-content\/uploads\/2022\/02\/Gardenia_FR-1.png\",\"contentUrl\":\"https:\/\/www.asterix-friends.com\/wp-content\/uploads\/2022\/02\/Gardenia_FR-1.png\",\"width\":700,\"height\":900},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asterix-friends.com\/fr\/asterix-ses-amis-remasterise-la-nouvelle-villageoise-taillefine\/\",\"url\":\"https:\/\/www.asterix-friends.com\/fr\/asterix-ses-amis-remasterise-la-nouvelle-villageoise-taillefine\/\",\"name\":\"Ast\u00e9rix & ses Amis remasteris\u00e9 - La nouvelle villageoise Taillefine - Asterix &amp; Friends - Official Website\",\"isPartOf\":{\"@id\":\"https:\/\/www.asterix-friends.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asterix-friends.com\/fr\/asterix-ses-amis-remasterise-la-nouvelle-villageoise-taillefine\/#primaryimage\"},\"datePublished\":\"2022-02-25T12:54:40+00:00\",\"dateModified\":\"2022-02-25T15:53:52+00:00\",\"author\":{\"@id\":\"https:\/\/www.asterix-friends.com\/de\/#\/schema\/person\/66f7d416a5240c4e566b0ea5ba384989\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.asterix-friends.com\/fr\/asterix-ses-amis-remasterise-la-nouvelle-villageoise-taillefine\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asterix-friends.com\/fr\/asterix-ses-amis-remasterise-la-nouvelle-villageoise-taillefine\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asterix-friends.com\/fr\/asterix-ses-amis-remasterise-la-nouvelle-villageoise-taillefine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.asterix-friends.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ast\u00e9rix &#038; ses Amis remasteris\u00e9 &#8211; La nouvelle villageoise Taillefine\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asterix-friends.com\/de\/#\/schema\/person\/66f7d416a5240c4e566b0ea5ba384989\",\"name\":\"Sarah\",\"url\":\"https:\/\/www.asterix-friends.com\/fr\/author\/sarah\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ast\u00e9rix & ses Amis remasteris\u00e9 - La nouvelle villageoise Taillefine - Asterix &amp; Friends - Official Website","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asterix-friends.com\/fr\/asterix-ses-amis-remasterise-la-nouvelle-villageoise-taillefine\/","twitter_misc":{"\u00c9crit par":"Sarah","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.asterix-friends.com\/de\/#website","url":"https:\/\/www.asterix-friends.com\/de\/","name":"Asterix &amp; Friends - Official Website","description":"Asterix &amp; Friends - the official Online and Mobile Game","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asterix-friends.com\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.asterix-friends.com\/fr\/asterix-ses-amis-remasterise-la-nouvelle-villageoise-taillefine\/#primaryimage","url":"https:\/\/www.asterix-friends.com\/wp-content\/uploads\/2022\/02\/Gardenia_FR-1.png","contentUrl":"https:\/\/www.asterix-friends.com\/wp-content\/uploads\/2022\/02\/Gardenia_FR-1.png","width":700,"height":900},{"@type":"WebPage","@id":"https:\/\/www.asterix-friends.com\/fr\/asterix-ses-amis-remasterise-la-nouvelle-villageoise-taillefine\/","url":"https:\/\/www.asterix-friends.com\/fr\/asterix-ses-amis-remasterise-la-nouvelle-villageoise-taillefine\/","name":"Ast\u00e9rix & ses Amis remasteris\u00e9 - La nouvelle villageoise Taillefine - Asterix &amp; Friends - Official Website","isPartOf":{"@id":"https:\/\/www.asterix-friends.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asterix-friends.com\/fr\/asterix-ses-amis-remasterise-la-nouvelle-villageoise-taillefine\/#primaryimage"},"datePublished":"2022-02-25T12:54:40+00:00","dateModified":"2022-02-25T15:53:52+00:00","author":{"@id":"https:\/\/www.asterix-friends.com\/de\/#\/schema\/person\/66f7d416a5240c4e566b0ea5ba384989"},"breadcrumb":{"@id":"https:\/\/www.asterix-friends.com\/fr\/asterix-ses-amis-remasterise-la-nouvelle-villageoise-taillefine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asterix-friends.com\/fr\/asterix-ses-amis-remasterise-la-nouvelle-villageoise-taillefine\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.asterix-friends.com\/fr\/asterix-ses-amis-remasterise-la-nouvelle-villageoise-taillefine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.asterix-friends.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Ast\u00e9rix &#038; ses Amis remasteris\u00e9 &#8211; La nouvelle villageoise Taillefine"}]},{"@type":"Person","@id":"https:\/\/www.asterix-friends.com\/de\/#\/schema\/person\/66f7d416a5240c4e566b0ea5ba384989","name":"Sarah","url":"https:\/\/www.asterix-friends.com\/fr\/author\/sarah\/"}]}},"_links":{"self":[{"href":"https:\/\/www.asterix-friends.com\/fr\/wp-json\/wp\/v2\/posts\/6791"}],"collection":[{"href":"https:\/\/www.asterix-friends.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asterix-friends.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asterix-friends.com\/fr\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asterix-friends.com\/fr\/wp-json\/wp\/v2\/comments?post=6791"}],"version-history":[{"count":2,"href":"https:\/\/www.asterix-friends.com\/fr\/wp-json\/wp\/v2\/posts\/6791\/revisions"}],"predecessor-version":[{"id":6793,"href":"https:\/\/www.asterix-friends.com\/fr\/wp-json\/wp\/v2\/posts\/6791\/revisions\/6793"}],"wp:attachment":[{"href":"https:\/\/www.asterix-friends.com\/fr\/wp-json\/wp\/v2\/media?parent=6791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asterix-friends.com\/fr\/wp-json\/wp\/v2\/categories?post=6791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asterix-friends.com\/fr\/wp-json\/wp\/v2\/tags?post=6791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}